{"id":2782,"date":"2025-06-09T09:45:34","date_gmt":"2025-06-09T09:45:34","guid":{"rendered":"https:\/\/butcombe.com\/the-george-inn-somerset\/?page_id=2782"},"modified":"2025-07-17T13:15:16","modified_gmt":"2025-07-17T13:15:16","slug":"wedding-venue-the-dungeon","status":"publish","type":"page","link":"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/","title":{"rendered":"The Dungeon For Weddings"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":64,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-standard-content.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2782","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Dungeon Wedding Pub Venue | Intimate Hire at Norton St. Philip<\/title>\n<meta name=\"description\" content=\"Say \u201cI do\u201d in The Dungeon at Norton St. Philip, a unique and intimate wedding venue steeped in history, perfect for private celebrations with character and charm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Dungeon Wedding Pub Venue | Intimate Hire at Norton St. Philip\" \/>\n<meta property=\"og:description\" content=\"Say \u201cI do\u201d in The Dungeon at Norton St. Philip, a unique and intimate wedding venue steeped in history, perfect for private celebrations with character and charm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/\" \/>\n<meta property=\"og:site_name\" content=\"The George Inn\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T13:15:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/wedding-venue-the-dungeon\\\/\",\"url\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/wedding-venue-the-dungeon\\\/\",\"name\":\"The Dungeon Wedding Pub Venue | Intimate Hire at Norton St. Philip\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/#website\"},\"datePublished\":\"2025-06-09T09:45:34+00:00\",\"dateModified\":\"2025-07-17T13:15:16+00:00\",\"description\":\"Say \u201cI do\u201d in The Dungeon at Norton St. Philip, a unique and intimate wedding venue steeped in history, perfect for private celebrations with character and charm.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/wedding-venue-the-dungeon\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/wedding-venue-the-dungeon\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/wedding-venue-the-dungeon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Dungeon For Weddings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/#website\",\"url\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/\",\"name\":\"The George Inn\",\"description\":\"Just another Butcombe Brewery Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/butcombe.com\\\/the-george-inn-somerset\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Dungeon Wedding Pub Venue | Intimate Hire at Norton St. Philip","description":"Say \u201cI do\u201d in The Dungeon at Norton St. Philip, a unique and intimate wedding venue steeped in history, perfect for private celebrations with character and charm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/","og_locale":"en_GB","og_type":"article","og_title":"The Dungeon Wedding Pub Venue | Intimate Hire at Norton St. Philip","og_description":"Say \u201cI do\u201d in The Dungeon at Norton St. Philip, a unique and intimate wedding venue steeped in history, perfect for private celebrations with character and charm.","og_url":"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/","og_site_name":"The George Inn","article_modified_time":"2025-07-17T13:15:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/","url":"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/","name":"The Dungeon Wedding Pub Venue | Intimate Hire at Norton St. Philip","isPartOf":{"@id":"https:\/\/butcombe.com\/the-george-inn-somerset\/#website"},"datePublished":"2025-06-09T09:45:34+00:00","dateModified":"2025-07-17T13:15:16+00:00","description":"Say \u201cI do\u201d in The Dungeon at Norton St. Philip, a unique and intimate wedding venue steeped in history, perfect for private celebrations with character and charm.","breadcrumb":{"@id":"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/butcombe.com\/the-george-inn-somerset\/wedding-venue-the-dungeon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/butcombe.com\/the-george-inn-somerset\/"},{"@type":"ListItem","position":2,"name":"The Dungeon For Weddings"}]},{"@type":"WebSite","@id":"https:\/\/butcombe.com\/the-george-inn-somerset\/#website","url":"https:\/\/butcombe.com\/the-george-inn-somerset\/","name":"The George Inn","description":"Just another Butcombe Brewery Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/butcombe.com\/the-george-inn-somerset\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/pages\/2782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/comments?post=2782"}],"version-history":[{"count":3,"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/pages\/2782\/revisions"}],"predecessor-version":[{"id":2809,"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/pages\/2782\/revisions\/2809"}],"wp:attachment":[{"href":"https:\/\/butcombe.com\/the-george-inn-somerset\/wp-json\/wp\/v2\/media?parent=2782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}